{"id":6353,"count":1,"description":"","link":"https:\/\/dviouscontent.com\/index.php\/tag\/flipper\/","name":"Flipper","slug":"flipper","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dviouscontent.com\/index.php\/wp-json\/wp\/v2\/tags\/6353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dviouscontent.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dviouscontent.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dviouscontent.com\/index.php\/wp-json\/wp\/v2\/posts?tags=6353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}